{"id":427,"count":1,"description":"<p data-start=\"990\" data-end=\"1113\">Inmuebles en La Asomada con Optima Estate, lanzarote inmobiliaria especializada en villa en Lanzarote y lanzarote casa seleccionadas.<\/p>\r\n<p data-start=\"1115\" data-end=\"1246\"><\/p>","link":"https:\/\/optimaestate.com\/es\/ciudad\/lanzarote-yaiza-casas-en-venta\/","name":"Casas en La Asomada, Lanzarote en venta","slug":"lanzarote-yaiza-casas-en-venta","taxonomy":"property_city","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/optimaestate.com\/es\/wp-json\/wp\/v2\/property_city\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optimaestate.com\/es\/wp-json\/wp\/v2\/property_city"}],"about":[{"href":"https:\/\/optimaestate.com\/es\/wp-json\/wp\/v2\/taxonomies\/property_city"}],"wp:post_type":[{"href":"https:\/\/optimaestate.com\/es\/wp-json\/wp\/v2\/properties?property_city=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}